{"id":54651,"date":"2022-05-05T17:00:50","date_gmt":"2022-05-05T20:00:50","guid":{"rendered":"http:\/\/aarquiteta.com.br\/?p=54651"},"modified":"2024-09-04T17:14:45","modified_gmt":"2024-09-04T20:14:45","slug":"como-inserir-imagem-no-autocad","status":"publish","type":"post","link":"https:\/\/www.aarquiteta.com.br\/blog\/como-inserir-imagem-no-autocad\/","title":{"rendered":"Imagem no AutoCAD &#8211; Coloque foto no seu projeto!"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter wp-image-54654 size-full\" title=\"Como inserir Imagem no AutoCAD - Coloque foto no seu projeto!\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/05\/como-colocar-imagem-no-autocad.jpg\" alt=\"Como inserir Imagem no AutoCAD - Coloque foto no seu projeto!\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/05\/como-colocar-imagem-no-autocad.jpg 1200w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/05\/como-colocar-imagem-no-autocad-1024x683.jpg 1024w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/05\/como-colocar-imagem-no-autocad-696x464.jpg 696w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/05\/como-colocar-imagem-no-autocad-150x100.jpg 150w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Imagem no AutoCAD &#8211; Coloque foto no seu projeto!<\/p>\n<p>Como inserir Imagem no AutoCAD &#8211; Coloque foto no seu projeto e crie apresenta\u00e7\u00f5es de impressionar seu cliente, professor, alunos&#8230;<\/p>\n<p>O segredo para realizar uma boa apresenta\u00e7\u00e3o de um projeto de arquitetura \u00e9 a ilustra\u00e7\u00e3o, por isso sempre que desenvolvemos um projeto arquitet\u00f4nico a etapa de cria\u00e7\u00e3o das imagens 3D enriquece o trabalho com imagens auto-explicativas.<\/p>\n<p>Neste artigo mostrarei como voc\u00ea pode <strong>colocar uma foto do seu projeto<\/strong> ou mesmo uma imagem 3D jpg <strong>na prancha final de apresenta\u00e7\u00e3o<\/strong> para o seu cliente ou mesmo para o seu professor na faculdade de arquitetura.<\/p>\n<figure id=\"attachment_28731\" aria-describedby=\"caption-attachment-28731\" style=\"width: 775px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-28731 size-full\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2019\/08\/primeira-colocada-blog-da-arquitetura.jpg\" alt=\"\" width=\"775\" height=\"549\" title=\"\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2019\/08\/primeira-colocada-blog-da-arquitetura.jpg 775w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2019\/08\/primeira-colocada-blog-da-arquitetura-696x493.jpg 696w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2019\/08\/primeira-colocada-blog-da-arquitetura-150x106.jpg 150w\" sizes=\"(max-width: 775px) 100vw, 775px\" \/><figcaption id=\"caption-attachment-28731\" class=\"wp-caption-text\">Como inserir Imagem no AutoCAD &#8211; Coloque foto no seu projeto! Imagem Blog da Arquitetura<\/figcaption><\/figure>\n<p><a href=\"https:\/\/www.aarquiteta.com.br\/curso-autocad-completo\/\" target=\"_blank\" rel=\"noopener\"><span class=\"JsGRdQ\" style=\"font-size: 24px; font-weight: bold;\">AUTOCAD <\/span><span style=\"font-size: 24px; font-weight: bold;\">INSERT IMAGE \u2014\u00a0 Como inserir Imagem no AutoCAD!<\/span><\/a><\/p>\n<p>1 \u2014 Confira as etapas b\u00e1sicas para inserir uma imagem jpg ou uma foto em seu projeto de arquitetura no AutoCAD.<\/p>\n<p>2 \u2014 Clique na guia Inserir -&gt; painel Refer\u00eancia-&gt; Anexar -&gt;\u00a0 Pesquisa<\/p>\n<p>3 \u2014 Na caixa de di\u00e1logo <strong>Selecionar arquivo de imagem,<\/strong> selecione um nome de arquivo na lista ou insira o nome do arquivo de imagem na caixa <strong>Nome do arquivo<\/strong>. Clique em Abrir.<\/p>\n<p>Na caixa de di\u00e1logo Imagem, utilize um dos seguintes m\u00e9todos para especificar o ponto de inser\u00e7\u00e3o, escala ou rota\u00e7\u00e3o:<\/p>\n<ul>\n<li>Selecione Especificar na tela para usar o dispositivo apontador para inserir a imagem no local, escala ou \u00e2ngulo que desejar.<\/li>\n<li>Desmarque Especificar na tela e insira valores em Ponto de inser\u00e7\u00e3o, Escala ou Rota\u00e7\u00e3o.<\/li>\n<\/ul>\n<p>4 \u2014 Para visualizar a unidade de medida para a imagem, clique em Detalhes. Clique em OK.<\/p>\n<h2 class=\"_04xlpA direction-ltr align-start para-style-title\"><a href=\"https:\/\/www.aarquiteta.com.br\/curso-de-arquitetura\/\" target=\"_blank\" rel=\"noopener\">e-TRANSMIT \u2014\u00a0 Como transportar uma Imagem no AutoCAD!<\/a><\/h2>\n<p>Quando trabalhamos com inser\u00e7\u00e3o de imagens em um arquivo no AutoCAD ela fica associada somente ao arquivo onde ela foi inicialmente inserida.<\/p>\n<p>Quando voc\u00ea seleciona um conjunto de arquivos de desenho no pacote de transmiss\u00e3o, ele inclui automaticamente todos os arquivos dependentes relacionados como refex e arquivos de fonte.<\/p>\n<p>Se for necess\u00e1rio compartilhar seu arquivo para outro computador ser\u00e1 necess\u00e1rio que voc\u00ea o feche primeiramente para a seguir transmiti-lo atrav\u00e9s do <strong>comando e-TRANSMIT<\/strong><\/p>\n<p>Este comando cria um pacote de arquivos (zip) para transmiss\u00e3o via Internet.<\/p>\n<p>Veja como \u00e9 simples utiliz\u00e1-lo:<\/p>\n<ol>\n<li>\u00a0Clique no \u00edcone de Pesquisa do seu AutoCAD;<\/li>\n<li>A caixa de di\u00e1logo Criar transmiss\u00e3o \u00e9 exibida.<\/li>\n<\/ol>\n<pre>Fonte: Transmiss\u00e3o de Arquivos por <a href=\"https:\/\/knowledge.autodesk.com\/pt-br\/support\/autocad\/learn-explore\/caas\/CloudHelp\/cloudhelp\/2019\/PTB\/AutoCAD-Core\/files\/GUID-413A58AD-C86F-432F-A4AC-A2737237001A-htm.html\" target=\"_blank\" rel=\"noopener\">Autodesk\u00a0<\/a><\/pre>\n<h3><a href=\"https:\/\/www.aarquiteta.com.br\/curso-autocad-completo\/\" target=\"_blank\" rel=\"noopener\">E a\u00ed, gostou do artigo sobre como inserir Imagem no AutoCAD \u2014 Coloque foto no seu projeto?<\/a><\/h3>\n<p>Esse conhecimento e muitos outros fazem parte do meu <a href=\"https:\/\/www.aarquiteta.com.br\/curso-autocad-completo\/\">curso de AutoCAD Projetos de Prefeitura<\/a>, onde al\u00e9m de aprender a desenhar voc\u00ea aprender\u00e1 a desenvolver projetos de arquitetura e prefeitura de forma muito f\u00e1cil e profissional, INCLUINDO <strong>como plotar no AutoCAD<\/strong> e principalmente <strong>como trabalhar com escalas<\/strong> corretamente!<\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/gYl6bPqn3y4\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Confira tamb\u00e9m este m\u00f3dulo do <a href=\"https:\/\/www.aarquiteta.com.br\/curso-autocad-completo\/\" target=\"_blank\" rel=\"noopener\"><strong>nosso curso voltado para o aluno<\/strong><\/a> que deseja aprender a criar <strong>um projeto completo<\/strong>, com plantas baixas, cortes, fachadas de maneira r\u00e1pida e sem aplicar as t\u00e9cnicas de aprova\u00e7\u00e3o de prefeitura, <strong>no caso de estudantes de arquitetura.<\/strong><a style=\"font-weight: bold; background-color: transparent;\" href=\"https:\/\/www.aarquiteta.com.br\/blog\/curso-de-autocad\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter wp-image-54568 size-full\" title=\"Como inserir Imagem no AutoCAD - Coloque foto no seu projeto!\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2021\/10\/curso-de-autocad-projetos-de-prefeitura.jpg\" alt=\"Como inserir Imagem no AutoCAD - Coloque foto no seu projeto!\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2021\/10\/curso-de-autocad-projetos-de-prefeitura.jpg 1200w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2021\/10\/curso-de-autocad-projetos-de-prefeitura-1024x683.jpg 1024w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2021\/10\/curso-de-autocad-projetos-de-prefeitura-696x464.jpg 696w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2021\/10\/curso-de-autocad-projetos-de-prefeitura-150x100.jpg 150w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p>Curso de AutoCAD Projetos de Prefeitura &#8211; Aprenda mais do que s\u00f3 um programa! <a href=\"https:\/\/www.aarquiteta.com.br\/blog\/curso-de-autocad\/\" target=\"_blank\" rel=\"noopener\">Clique aqui para saber mais!<\/a>Com ele ser\u00e1 poss\u00edvel <strong>desenvolver os projetos de estudo da faculdade<\/strong> incluindo o <strong>TCC<\/strong>, veja o video acelerado do que voc\u00ea aprender\u00e1:<\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/GkooAkWVTCw\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_54491\" aria-describedby=\"caption-attachment-54491\" style=\"width: 1080px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.aarquiteta.com.br\/curso-autocad-completo\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-54491 size-full\" title=\"Como inserir Imagem no AutoCAD - Coloque foto no seu projeto!\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/06\/curso-de-autocad-completo.jpeg\" alt=\"curso de autocad completo\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/06\/curso-de-autocad-completo.jpeg 1080w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/06\/curso-de-autocad-completo-1024x1024.jpeg 1024w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/06\/curso-de-autocad-completo-696x696.jpeg 696w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/06\/curso-de-autocad-completo-96x96.jpeg 96w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/06\/curso-de-autocad-completo-150x150.jpeg 150w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><figcaption id=\"caption-attachment-54491\" class=\"wp-caption-text\">Curso de AutoCAD completo profissional &#8211; <a href=\"https:\/\/www.aarquiteta.com.br\/curso-autocad-completo\/\" target=\"_blank\" rel=\"noopener\">Clique para ver mais!<\/a><\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imagem no AutoCAD &#8211; Coloque foto no seu projeto! Como inserir Imagem no AutoCAD &#8211; Coloque foto no seu projeto e crie apresenta\u00e7\u00f5es de impressionar seu cliente, professor, alunos&#8230; O segredo para realizar uma boa apresenta\u00e7\u00e3o de um projeto de arquitetura \u00e9 a ilustra\u00e7\u00e3o, por isso sempre que desenvolvemos um projeto arquitet\u00f4nico a etapa de [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":54654,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33404],"tags":[18126,18127,18128,18129],"class_list":["post-54651","post","type-post","status-publish","format-standard","has-post-thumbnail","category-autocad","tag-como-atachar-imagem-no-autocad","tag-como-colocar-imagem-no-autocad","tag-como-configurar-imagem-no-autocad","tag-como-salvar-imagem-no-autocad"],"_wp_attached_file":null,"_wp_attachment_metadata":null,"_wp_attachment_context":null,"_wp_attachment_is_custom_header":null,"geo_longitude":null,"geo_public":null,"geo_latitude":null,"_publicize_done_external":null,"_wpas_done_3897181":null,"publicize_twitter_user":null,"_wpas_done_3897175":null,"_wpas_skip_3897181":null,"_wpas_skip_3897175":null,"_wpas_skip_3924723":null,"_wpas_mess":null,"_wpas_done_3924723":null,"wps_subtitle":"Confira neste artigo as dicas sobre o programa mais conhecido no mercado da constru\u00e7\u00e3o civil!","_links":{"self":[{"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/posts\/54651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=54651"}],"version-history":[{"count":0,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/posts\/54651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/media\/54654"}],"wp:attachment":[{"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=54651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=54651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=54651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}