{"id":54478,"date":"2022-06-06T11:00:57","date_gmt":"2022-06-06T14:00:57","guid":{"rendered":"http:\/\/aarquiteta.com.br\/?p=54478"},"modified":"2024-09-15T08:47:42","modified_gmt":"2024-09-15T11:47:42","slug":"como-colocar-escala-no-autocad","status":"publish","type":"post","link":"https:\/\/www.aarquiteta.com.br\/blog\/como-colocar-escala-no-autocad\/","title":{"rendered":"Escala AutoCAD &#8211; Veja como colocar escala no seu desenho!"},"content":{"rendered":"<p>Como colocar escala no <a href=\"https:\/\/www.aarquiteta.com.br\/blog\/cursos-de-arquitetura-e-decoracao\/autocad-cursos\/\">AutoCAD<\/a> \u2014 Veja na pr\u00e1tica como fazer na pr\u00e1tica assista ao video completo!<\/p><p>Ao iniciar um <a href=\"https:\/\/www.aarquiteta.com.br\/blog\/?s=DESENHO\">desenho<\/a> no AutoCAD \u00e9 muito importante que voc\u00ea defina a escala em que voc\u00ea desenvolver\u00e1 seus desenhos, iniciar um trabalho sem conhecer as unidades de medida do arquivo pode causar muito retrabalho.<\/p><p>Confira neste artigo as dicas de como mudar a <strong>escala de trabalho no AutoCAD<\/strong> e de quebra ainda te ensinarei como configurar a <strong>escala de inser\u00e7\u00e3o de objetos<\/strong> (bloco) para que nunca mais importe um bloco pequeno ou exageradamente grande demais!<\/p><h2><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/autocad-online\/\" target=\"_blank\" rel=\"noopener\">Escala AutoCAD &#8211; Veja como colocar escala no seu desenho!<\/a><\/h2><p>Muito erroneamente se acredita que\u00a0 o AutoCAD possui um bot\u00e3o m\u00e1gico de configura\u00e7\u00e3o de escalas, onde o tamanho dos textos, dos objetos, das hachuras, das linhas e cores fiquem todas em concord\u00e2ncia com o desenho que estamos desenvolvendo.<\/p><p>Na verdade, o que temos no AutoCAD \u00e9 uma pr\u00e9-configura\u00e7\u00e3o de sistema de unidade decimal trabalhando em conjunto com outros sistemas de medida.<\/p><p>O comando UNIDADES (_UNITS)\u00a0 controla a precis\u00e3o e os formatos de exibi\u00e7\u00e3o de coordenadas, dist\u00e2ncias e \u00e2ngulos.<\/p><p>O formato, a precis\u00e3o e outras configura\u00e7\u00f5es utilizadas para a exibi\u00e7\u00e3o de coordenadas, dist\u00e2ncias e \u00e2ngulos s\u00e3o definidas atrav\u00e9s desta caixa de di\u00e1logo, salvas no desenho atual.<\/p><p><iframe style=\"width: 120px; height: 240px;\" src=\"\/\/ws-na.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=BR&amp;source=ss&amp;ref=as_ss_li_til&amp;ad_type=product_link&amp;tracking_id=aarquiteta-20&amp;language=pt_BR&amp;marketplace=amazon&amp;region=BR&amp;placement=8561453443&amp;asins=8561453443&amp;linkId=270820f75c42ca0a4acd8d41c495df99&amp;show_border=true&amp;link_opens_in_new_window=true\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-popups allow-scripts allow-modals allow-forms allow-same-origin\"><\/iframe><\/p><h3><a href=\"https:\/\/www.aarquiteta.com.br\/curso-de-arquitetura\/\" target=\"_blank\" rel=\"noopener\">Confira o passo a passo de como mudar a escala do AutoCAD:<\/a><\/h3><p>Use este procedimento para especificar unidades de desenho em desenhos novos ou existentes.<\/p><p>Se voc\u00ea alterar as unidades de desenho, voc\u00ea tamb\u00e9m poder\u00e1 especificar se os objetos existentes no desenho ser\u00e3o dimensionados para as novas unidades ou manter\u00e3o seu tamanho original.<\/p><p>Voc\u00ea tamb\u00e9m pode especificar se os objetos inseridos de desenhos que usam unidades diferentes s\u00e3o dimensionados para as unidades do desenho atual ou permanecem em seu tamanho original.<\/p><p>Voc\u00ea pode especificar o tipo de unidade e a precis\u00e3o para unidades lineares, angulares, de \u00e1rea e de volume.<\/p><p>O valor de precis\u00e3o espec\u00edfica apenas o n\u00famero de <a href=\"https:\/\/www.aarquiteta.com.br\/blog\/?s=CASAS\">casas<\/a> decimais exibidas na interface. Eles n\u00e3o t\u00eam certeza sobre o n\u00famero de casas decimais usadas no c\u00e1lculo no software.<\/p><p>Ao alterar as unidades de desenho, as op\u00e7\u00f5es padr\u00e3o em \u00c1rea e Volume mudam para refletir as novas unidades de desenho. As op\u00e7\u00f5es de escala de desenho na guia Escala tamb\u00e9m mudam para refletir as novas unidades de desenho.<\/p><figure id=\"attachment_54352\" aria-describedby=\"caption-attachment-54352\" style=\"width: 534px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-54352 size-full\" title=\"Como colocar escala no AutoCAD - Veja na pr\u00e1tica como fazer!\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/05\/como-mudar-a-escala-do-autocad.png\" alt=\"Como colocar escala no AutoCAD - Veja na pr\u00e1tica como fazer!\" width=\"534\" height=\"545\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/05\/como-mudar-a-escala-do-autocad.png 534w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/05\/como-mudar-a-escala-do-autocad-150x153.png 150w\" sizes=\"(max-width: 534px) 100vw, 534px\" \/><figcaption id=\"caption-attachment-54352\" class=\"wp-caption-text\">Como colocar escala no AutoCAD &#8211; Veja na pr\u00e1tica como fazer!<\/figcaption><\/figure><h2><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/autocad-online\/\" target=\"_blank\" rel=\"noopener\">Como mudar a escala de Inser\u00e7\u00e3o do Bloco no AutoCAD?<\/a><\/h2><p>Se voc\u00ea \u00e9 colecionador de blocos de AutoCAD voc\u00ea j\u00e1 deve ter notado que algumas vezes ao importar o seu bloco ou objeto no desenho ele se mostra totalmente fora da escala, mas porque isso acontece? Vejamos a seguir.<\/p><h3><a href=\"https:\/\/www.aarquiteta.com.br\/curso-de-arquitetura\/\" target=\"_blank\" rel=\"noopener\">Onde voc\u00ea plota seu desenho? No Model ou no Layout?<\/a><\/h3><p>A configura\u00e7\u00e3o da escala de um desenho depender\u00e1 da forma como voc\u00ea desenvolve o desenho, pois o AutoCAD n\u00e3o trabalha com uma escala em espec\u00edfico.<\/p><p>O plano XY do AutoCAD, por exemplo:<\/p><p>Para ele 1 unidade pode significar 1m, 1mm, 1cm, ou 1km.<\/p><p>Na verdade, pode significar o que voc\u00ea determinar!<\/p><p>Por isso \u00e9 importante que antes de come\u00e7ar o seu desenho voc\u00ea configure as escalas que ir\u00e1 utilizar em seu <a href=\"https:\/\/www.aarquiteta.com.br\/blog\/?s=PROJETO\">projeto<\/a>.<\/p><figure id=\"attachment_4280\" aria-describedby=\"caption-attachment-4280\" style=\"width: 1364px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-4280 size-full\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2014\/11\/projetos-modelo.png\" alt=\"\" width=\"1364\" height=\"720\" title=\"\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2014\/11\/projetos-modelo.png 1364w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2014\/11\/projetos-modelo-1024x541.png 1024w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2014\/11\/projetos-modelo-696x367.png 696w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2014\/11\/projetos-modelo-150x79.png 150w\" sizes=\"(max-width: 1364px) 100vw, 1364px\" \/><figcaption id=\"caption-attachment-4280\" class=\"wp-caption-text\">Como colocar escala no AutoCAD &#8211; Veja na pr\u00e1tica como fazer!<\/figcaption><\/figure><p>Isso \u00e9 muito importante, pois em uma mesma prancha voc\u00ea pode ter 2 ou mais escalas e voc\u00ea n\u00e3o deve <strong>jamais<\/strong> escalonar ou escalar desenhos no Model, a \u00e1rea onde de desenvolve os desenhos.<\/p><p>Para voc\u00ea utilizar escalas diferentes em uma mesma prancha \u00e9 que necess\u00e1rio que voc\u00ea utilize a \u00e1rea de impress\u00e3o, para isso existe o Layout.<\/p><h3><iframe style=\"width: 120px; height: 240px;\" src=\"\/\/ws-na.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=BR&amp;source=ss&amp;ref=as_ss_li_til&amp;ad_type=product_link&amp;tracking_id=aarquiteta-20&amp;language=pt_BR&amp;marketplace=amazon&amp;region=BR&amp;placement=8561453443&amp;asins=8561453443&amp;linkId=270820f75c42ca0a4acd8d41c495df99&amp;show_border=true&amp;link_opens_in_new_window=true\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-popups allow-scripts allow-modals allow-forms allow-same-origin\"><\/iframe><\/h3><h3>Nunca escale objetos!<\/h3><p>Supomos que voc\u00ea precise de um bloco com dimens\u00f5es maiores que a escala em que voc\u00ea est\u00e1 desenhando.<\/p><p>Se voc\u00ea escalar um bloco de vegeta\u00e7\u00e3o, por exemplo, em um fator de 0.5 para transformar um desenho em escala 1:200, pode apostar que isso causar\u00e1 um transtorno sem igual.<\/p><p>O problema principal ser\u00e1 a cota. Tudo o que for cotado ter\u00e1 o seu valor reduzido pela metade.<\/p><p>O segundo problema ser\u00e1\u00a0 a configura\u00e7\u00e3o dos textos, sair\u00e3o todos da altura padr\u00e3o.<\/p><p>Se houver altera\u00e7\u00e3o do desenho ser\u00e1 necess\u00e1rio re-escalar tudo novamente. Imagine uma vida de vai e volta de escalas? Nada pr\u00e1tico.<\/p><p>Por isso existe o Layout! Nele voc\u00ea poder\u00e1 trabalhar com escalas 1:100, 1:50, 1:20. 1:5,1:1 de maneira correta e eficiente.<\/p><p>Pois, quando voc\u00ea criar as escalas \u00e9 que voc\u00ea poder\u00e1 atribuir ao seu desenho atrav\u00e9s do que chamamos <strong>VIEWPORT.<\/strong><\/p><figure id=\"attachment_4282\" aria-describedby=\"caption-attachment-4282\" style=\"width: 1366px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-4282 size-full\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2014\/11\/template.png\" alt=\"\" width=\"1366\" height=\"728\" title=\"\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2014\/11\/template.png 1366w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2014\/11\/template-1024x546.png 1024w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2014\/11\/template-696x371.png 696w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2014\/11\/template-150x80.png 150w\" sizes=\"(max-width: 1366px) 100vw, 1366px\" \/><figcaption id=\"caption-attachment-4282\" class=\"wp-caption-text\">Como colocar escala no AutoCAD &#8211; Veja na pr\u00e1tica como fazer!<\/figcaption><\/figure><h3>Como mudar a escala no AutoCAD \u2014 Veja na pr\u00e1tica como fazer!<\/h3><p>Ent\u00e3o chega de teoria e vamos \u00e0 pr\u00e1tica!<\/p><p>Assista agora a video aula onde mostro na pr\u00e1tica como mudar a escala do AutoCAD,\u00a0 tanto a de trabalho como a de inser\u00e7\u00e3o de blocos e deix\u00e1-la na escala correta!<\/p><p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/LsAiLA7zvoc\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p><h2><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/autocad-online\/\" target=\"_blank\" rel=\"noopener\">Como mudar a escala no AutoCAD \u2014 Acerte no tamanho do bloco de uma vez por todas!<\/a><\/h2><h3>Como mudar a escala no AutoCAD &#8211; Dicas finais:<\/h3><p>Adote uma escala de trabalho e utilize-a no layout para impress\u00e3o de desenhos em folhas com diferentes tamanhos ou escalas. Vale a pena e \u00e9 super f\u00e1cil.<\/p><p>Exceto pelos detalhes de projeto que n\u00e3o mudam nunca, como de uma escada, duto de passagem e outros.<\/p><p><strong>Adotar uma escala de trabalho<\/strong> mais conveniente ao seu trabalho vai lhe ajudar tamb\u00e9m na compreens\u00e3o e manipula\u00e7\u00e3o de inser\u00e7\u00e3o de blocos vindos de terceiros.<\/p><p style=\"text-align: justify;\">Adote sistemas e rotinas de trabalho saud\u00e1veis de modo a gerar um <strong>Template Sadio<\/strong> que a cada projeto, o mesmo evolua em qualidade e possa ser devidamente utilizado e compartilhado entre outros usu\u00e1rios, sem distor\u00e7\u00e3o de elementos ou perca de informa\u00e7\u00e3o.<\/p><p>Trabalhe sempre buscando adotar as<a href=\"https:\/\/www.aarquiteta.com.br\/blog\/desenho-arquitetonico-no-autocad\/\" target=\"_blank\" rel=\"noopener\"> Boas Pr\u00e1ticas na Elabora\u00e7\u00e3o de Desenhos Arquitet\u00f4nicos<\/a> especialmente no AutoCAD e tenha um desenho saud\u00e1vel que ao ser compartilhado n\u00e3o causar\u00e1 problemas ou confus\u00e3o ao ser alterado.<\/p><p><span style=\"font-size: 22px; font-weight: bold; color: #2b2b2b;\">E a\u00ed, gostou do artigo sobre <a href=\"https:\/\/www.aarquiteta.com.br\/blog\/autocad-online\/\" target=\"_blank\" rel=\"noopener\">Escala AutoCAD &#8211; Veja como colocar escala no seu desenho!<\/a><\/span><\/p><p>Ent\u00e3o deslize a tela para baixo e<a href=\"https:\/\/br.pinterest.com\/aarquitetapinterest\/_created\/\" target=\"_blank\" rel=\"noopener\"> confira mais dicas<\/a> como esta e n\u00e3o se esque\u00e7a de compartilhar com os amigos!<\/p><p>Quer mais dicas sobre o mundo da <a href=\"https:\/\/www.aarquiteta.com.br\/blog\/?s=ARQUITETURA\">Arquitetura<\/a> e Decora\u00e7\u00e3o, ent\u00e3o confira alguns dos nossos artigos em:<\/p><ul><li><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/paisagismo\/\" target=\"_blank\" rel=\"noopener\">Casa e Jardim<\/a><\/li><li><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/arquitetura\/mundo-arquitetura\/\" target=\"_blank\" rel=\"noopener\">Mundo Arquitetura<\/a><\/li><li><a href=\"https:\/\/www.aarquiteta.com.br\/decoracao\/\" target=\"_blank\" rel=\"noopener\">Decora\u00e7\u00e3o<br \/>\n<\/a><\/li><\/ul><p>Quando se trabalha no\u00a0<a href=\"https:\/\/www.aarquiteta.com.br\/curso-autocad-completo\/\">AutoCAD<\/a> \u00e9 preciso saber como configurar escalas.<strong>\u00a0<\/strong>No artigo anterior falei sobre como plotar no AutoCAD e nele expliquei como se calcular as escalas corretamente.<\/p><p>Como mudar a escala no AutoCAD &#8211; Acerte no tamanho do bloco!<\/p>","protected":false},"excerpt":{"rendered":"<p>Como colocar escala no AutoCAD \u2014 Veja na pr\u00e1tica como fazer na pr\u00e1tica assista ao video completo!Ao iniciar um desenho no AutoCAD \u00e9 muito importante que voc\u00ea defina a escala em que voc\u00ea desenvolver\u00e1 seus desenhos, iniciar um trabalho sem conhecer as unidades de medida do arquivo pode causar muito retrabalho.Confira neste artigo as dicas [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":70770,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33404],"tags":[18067,18417,18069,18070,18071],"class_list":["post-54478","post","type-post","status-publish","format-standard","has-post-thumbnail","category-autocad","tag-como-colocar-bloco-na-escala","tag-como-colocar-escala-no-autocad","tag-como-escalar-bloco","tag-como-escalar-bloco-autocad","tag-como-mudar-a-escala-do-bloco"],"_wp_attached_file":null,"_wp_attachment_metadata":null,"_wp_attachment_context":null,"_wp_attachment_is_custom_header":null,"geo_longitude":null,"geo_public":null,"geo_latitude":null,"_publicize_done_external":null,"_wpas_done_3897181":null,"publicize_twitter_user":null,"_wpas_done_3897175":null,"_wpas_skip_3897181":null,"_wpas_skip_3897175":null,"_wpas_skip_3924723":null,"_wpas_mess":null,"_wpas_done_3924723":null,"wps_subtitle":"Aprenda como mudar a escala no AutoCAD e nunca mais perca tempo escalando bloco em seus desenhos!","_links":{"self":[{"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/posts\/54478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=54478"}],"version-history":[{"count":0,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/posts\/54478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/media\/70770"}],"wp:attachment":[{"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=54478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=54478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=54478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}