{"id":10050,"date":"2021-10-15T01:00:19","date_gmt":"2021-10-15T04:00:19","guid":{"rendered":"http:\/\/aarquiteta.com.br\/?p=10050"},"modified":"2024-09-04T18:07:20","modified_gmt":"2024-09-04T21:07:20","slug":"lavabo","status":"publish","type":"post","link":"https:\/\/www.aarquiteta.com.br\/blog\/lavabo\/","title":{"rendered":"Lavabo &#8211; Como fazer a reforma dos seus sonhos!"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter wp-image-50566 size-full\" title=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/04\/Reforma-de-Lavabo-.jpg\" alt=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/04\/Reforma-de-Lavabo-.jpg 1200w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/04\/Reforma-de-Lavabo--1024x683.jpg 1024w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/04\/Reforma-de-Lavabo--696x464.jpg 696w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2022\/04\/Reforma-de-Lavabo--150x100.jpg 150w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p><p><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/cursos-de-arquitetura-e-decoracao\/curso-de-gerenciamento-de-obras\">Reforma<\/a> de Lavabo \u2014 Como fazer a reforma dos seus sonhos!<\/p><p><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/?s=quarto\">Lavabo<\/a>: seja ele pequeno, bonito e funcional muitas vezes n\u00e3o \u00e9 t\u00e3o dif\u00edcil deix\u00e1-lo como imaginamos.<\/p><p>Com a infinidade de op\u00e7\u00f5es de recursos, objetos de decora\u00e7\u00e3o e utens\u00edlios que temos no mercado \u00e9 poss\u00edvel realizar muito com pouco.<\/p><p>No entanto, para criar um ambiente que realmente inspire admira\u00e7\u00e3o \u00e9 preciso um pouco mais de transpira\u00e7\u00e3o.<\/p><p>\u00c9 preciso, claro, investimento.<\/p><p>Por isso neste artigo falaremos sobre como projetar lavabos, especificamente de apartamentos, o cart\u00e3o de visitas da sua casa.<\/p><p>Tenha um lavabo lindo para chamar de seu e impressionar seus convidados com estilo.<\/p><h3>Reforma de Lavabo \u2014 Afinal, o que \u00e9 um Lavabo?<\/h3><p>Localizado estrategicamente pr\u00f3ximo ao <a href=\"https:\/\/www.aarquiteta.com.br\/blog\/?s=HALL\">hall<\/a> de entrada, temos como defini\u00e7\u00e3o de WC (Wather Closet) um pequeno ambiente fechado com acesso \u00e0 \u00e1gua para realiza\u00e7\u00e3o de pequenas higienes pessoais.<\/p><p>Defini\u00e7\u00e3o fria e sem gra\u00e7a, \u00e9 mentira.<\/p><p>O lavabo, na verdade, geralmente \u00e9 o menor c\u00f4modo dentro de uma edifica\u00e7\u00e3o, e como seu uso \u00e9 destinado \u00e0s visitas, sempre caprichamos para agradar os nossos convidados.\u00a0 \u00c9 o ambiente onde seu convidado pode se sentir confort\u00e1vel para admirar os detalhes da decora\u00e7\u00e3o sem ser pego de surpresa ca\u00eddo de admira\u00e7\u00e3o.<\/p><p>Se o assunto interessou fique ligado!<\/p><h2>Reforma de Lavabo &#8211; Como fazer a reforma dos seus sonhos?<\/h2><h3><strong>Layout<br \/>\n<\/strong><\/h3><p>Sabemos que em um lavado a circula\u00e7\u00e3o \u00e9 realmente m\u00ednima, n\u00e3o h\u00e1 muito o que se fazer quanto a sua <a href=\"https:\/\/www.aarquiteta.com.br\/blog\/?s=ARQUITETURA\">arquitetura<\/a>, principalmente quando se trata da reforma de um apartamento.<\/p><p>Mas em alguns casos, uma ou duas interfer\u00eancias j\u00e1 s\u00e3o suficientes para dar um ar de personalidade a esse cantinho t\u00e3o querido em nossa casa.<\/p><p>Encontramos frequentemente projetos de reforma para apartamentos que apresentam apenas o\u00a0b\u00e1sico do b\u00e1sico:<\/p><figure id=\"attachment_10096\" aria-describedby=\"caption-attachment-10096\" style=\"width: 592px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-10096 size-full\" title=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo_antes_e_depois.jpg\" alt=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" width=\"592\" height=\"879\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo_antes_e_depois.jpg 592w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo_antes_e_depois-150x223.jpg 150w\" sizes=\"(max-width: 592px) 100vw, 592px\" \/><figcaption id=\"caption-attachment-10096\" class=\"wp-caption-text\">Reforma de Lavabo &#8211; Como fazer a reforma dos seus sonhos!<\/figcaption><\/figure><p>Um tampo de pia, uma cuba e os revestimentos de <a href=\"https:\/\/www.aarquiteta.com.br\/blog\/?s=PISO\">piso<\/a>, claro que tudo de gosto meio duvidoso (imagem do antes).<\/p><p>E nesse modelo de apartamento que mostraremos para voc\u00eas algumas ideias para tornar seu lavabo frio e c\u00e1lido em lavabo digno de aplausos.<\/p><p>A primeira op\u00e7\u00e3o de projeto adotada foi a possibilidade de alterar o ponto de sa\u00edda da bacia sanit\u00e1ria.<\/p><p>Nesse caso em apartamentos \u00e9 preciso pedir a autoriza\u00e7\u00e3o do vizinho do apartamento de baixo para este permitir que voc\u00ea acesse o forro do banheiro dele, j\u00e1 que a rede hidr\u00e1ulica do seu lavabo passa em cima do lavado dele.<\/p><p>Visto que isso \u00e9 poss\u00edvel, tudo fica lindo!<\/p><p>A mudan\u00e7a do ponto do esgoto promove um ganho de \u00e1rea de bancada assim garantimos um layout mais amistoso aos olhos de quem adentra o ambiente.<\/p><figure id=\"attachment_10051\" aria-describedby=\"caption-attachment-10051\" style=\"width: 555px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/Projeto-de-Lavabo.jpg\"><img decoding=\"async\" class=\"wp-image-10051\" title=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/Projeto-de-Lavabo.jpg\" alt=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" width=\"555\" height=\"610\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/Projeto-de-Lavabo.jpg 428w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/Projeto-de-Lavabo-150x165.jpg 150w\" sizes=\"(max-width: 555px) 100vw, 555px\" \/><\/a><figcaption id=\"caption-attachment-10051\" class=\"wp-caption-text\">Reforma de Lavabo &#8211; Como fazer a reforma dos seus sonhos!<\/figcaption><\/figure><p>Contudo, se isso n\u00e3o for poss\u00edvel, ou seja, se n\u00e3o for permitida a mudan\u00e7a de ponto da bacia, o que infelizmente foi o nosso caso.<\/p><p>Por isso, tivemos que trabalhar com o que nos foi permitido fazer, continuar com o layout inicial que apesar dos percal\u00e7os n\u00e3o foi de todo ruim.<\/p><p>&nbsp;<\/p><figure id=\"attachment_10053\" aria-describedby=\"caption-attachment-10053\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-reforma-apto.jpg\"><img decoding=\"async\" class=\"wp-image-10053\" title=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-reforma-apto.jpg\" alt=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" width=\"600\" height=\"800\" \/><\/a><figcaption id=\"caption-attachment-10053\" class=\"wp-caption-text\">Reforma de Lavabo &#8211; Como fazer a reforma dos seus sonhos!<\/figcaption><\/figure><p>A vantagem principal de mudar o ponto de sa\u00edda da bacia sanit\u00e1ria para frente da porta era de se\u00a0<strong>ganhar uma maior \u00e1rea de bancada<\/strong> com um bom espa\u00e7o para <strong>distribuir elementos de decora\u00e7\u00e3o,<\/strong> por exemplo.<\/p><p>Nesse caso um bel\u00edssimo kit de utens\u00edlios para lavabo daria aquele lindo toque de organiza\u00e7\u00e3o no ambiente.<\/p><h3>Acabamento \u2014 texturas e materiais.<\/h3><p>Sabe aquele tom claro que pensamos sempre\u00a0 para o banheiro principal da nossa casa?<\/p><p><strong>Esque\u00e7a!<\/strong><\/p><p>Se voc\u00ea curte uns tons mais escuros no lavabo voc\u00ea pode usar e abusar de texturas escuras, por exemplo.<\/p><p>Claro que sempre com muito equil\u00edbrio.<\/p><p>Apesar de ser um ambiente de curta perman\u00eancia pelo usu\u00e1rio, a experi\u00eancia tem que ser agrad\u00e1vel.<\/p><p>Um tom mais escuro para o lavabo proporciona um ar mais <strong>intimista e sofisticado<\/strong>.<\/p><p>Acabamentos em madeira e revestimentos texturizados de efeito 3D, tamb\u00e9m s\u00e3o sempre bem vindos nesses ambientes.<\/p><p>Contudo, \u00e9 necess\u00e1rio ter muito cuidado para n\u00e3o carregar demais!<\/p><h4>E quanto ao piso?<\/h4><p>Est\u00e1 cada vez mais em uso adotar o piso da sala como o piso do lavabo, pois \u00a0proporciona unidade e agrega design ao conjunto.<\/p><p>\u00c9 como se a sala nos convidasse a conhecer o lavabo.<\/p><figure id=\"attachment_10060\" aria-describedby=\"caption-attachment-10060\" style=\"width: 768px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo.jpg\"><img decoding=\"async\" class=\"wp-image-10060 size-full\" title=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo.jpg\" alt=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" width=\"768\" height=\"1024\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo.jpg 768w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-696x928.jpg 696w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-640x853.jpg 640w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-150x200.jpg 150w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><figcaption id=\"caption-attachment-10060\" class=\"wp-caption-text\">Reforma de Lavabo &#8211; Como fazer a reforma dos seus sonhos!<\/figcaption><\/figure><h3 style=\"text-align: left;\">Reforma de Lavabo &#8211; Design \u00e9 tudo!<\/h3><p>Esta na hora de escolher lou\u00e7as e metais que eles mais aparecem!<\/p><p>Bacias sanit\u00e1rias minimalistas com linhas retas e assentos sanit\u00e1rios tecnol\u00f3gicos valorizam em muito o ambiente.<\/p><figure id=\"attachment_10005\" aria-describedby=\"caption-attachment-10005\" style=\"width: 720px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-10005 size-full\" title=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/rocca_sanitario.jpeg\" alt=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" width=\"720\" height=\"540\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/rocca_sanitario.jpeg 720w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/rocca_sanitario-696x522.jpeg 696w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/rocca_sanitario-150x113.jpeg 150w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><figcaption id=\"caption-attachment-10005\" class=\"wp-caption-text\">Reforma de Lavabo &#8211; Como fazer a reforma dos seus sonhos!<\/figcaption><\/figure><p style=\"text-align: center;\">\u00a0Exemplo de bacia sanit\u00e1ria<\/p><h3>Os metais s\u00e3o a cereja do bolo em um Lavabo!<\/h3><p>Utilizamos o modelo de torneira Polo da Deca de bancada, mas est\u00e1 muito na moda utilizar torneiras de parede, ambas s\u00e3o lindas.<\/p><figure id=\"attachment_10056\" aria-describedby=\"caption-attachment-10056\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/torneira-polo-lavabo.jpg\"><img decoding=\"async\" class=\"wp-image-10056\" title=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/torneira-polo-lavabo.jpg\" alt=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" width=\"800\" height=\"534\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/torneira-polo-lavabo.jpg 1600w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/torneira-polo-lavabo-1024x683.jpg 1024w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/torneira-polo-lavabo-696x464.jpg 696w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/torneira-polo-lavabo-150x100.jpg 150w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-10056\" class=\"wp-caption-text\">Torneira Polo Deca<\/figcaption><\/figure><p style=\"text-align: left;\">\u00c9 muito importante escolher a torneira correta com as dimens\u00f5es compat\u00edveis com a cuba da pia para que esta n\u00e3o acabe ficando pequena, curta ou grande demais.<\/p><p style=\"text-align: left;\">As empresas de lou\u00e7as e metais sempre fornecem as dimens\u00f5es t\u00e9cnicas em seus cat\u00e1logos on-line.<\/p><p style=\"text-align: left;\">Certifique-se que o modelo escolhido tenha o tamanho ideal antes de finalizar a compra.<\/p><figure id=\"attachment_10057\" aria-describedby=\"caption-attachment-10057\" style=\"width: 547px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/dimens\u00f5es-da-polo.jpg\"><img decoding=\"async\" class=\"wp-image-10057\" title=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/dimens\u00f5es-da-polo-424x500.jpg\" alt=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" width=\"547\" height=\"720\" \/><\/a><figcaption id=\"caption-attachment-10057\" class=\"wp-caption-text\">Desenho T\u00e9cnico Torneira Polo Deca<\/figcaption><\/figure><p>&nbsp;<\/p><p style=\"text-align: left;\">N\u00e3o \u00e9 preciso nem falar que a bancada deve ser bem trabalhada tanto na forma como no material.<\/p><p style=\"text-align: left;\">No nosso lavabo projetamos uma bancada com a cuba esculpida em Corian branco com o detalhe em vidro.<\/p><p style=\"text-align: left;\">N\u00e3o d\u00e1 para dizer que n\u00e3o ficou bom, mas poderia ter ficado maravilhosa se o vizinho de baixo tivesse permitido o acesso ao forro, assim ter\u00edamos trocado o ponto da bacia de lugar, a bancada seria maior e o layout seria encantador.<\/p><figure id=\"attachment_10058\" aria-describedby=\"caption-attachment-10058\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-detalhe.jpg\"><img decoding=\"async\" class=\"wp-image-10058 size-full\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-detalhe.jpg\" alt=\"\" width=\"900\" height=\"1200\" title=\"\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-detalhe.jpg 900w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-detalhe-768x1024.jpg 768w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-detalhe-696x928.jpg 696w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-detalhe-640x853.jpg 640w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-detalhe-150x200.jpg 150w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><figcaption id=\"caption-attachment-10058\" class=\"wp-caption-text\">Detalhe da Cuba\u00a0no lavabo<\/figcaption><\/figure><p>.<\/p><h3><strong>Espelho no lavabo<\/strong><\/h3><p>No caso desse lavabo al\u00e9m do espelho principal optamos por revestir a parede com um espelho marrom mais fosco em todo o projeto.<\/p><p>Esse foi o ponto alto do projeto, pois com o barrado zebrado em MDF na altura da pia para baixo, conferiu um ambiente ainda mais intimista ao ambiente.<\/p><h3>Nicho<\/h3><p>Quer deixar ainda mais bonito?<\/p><p>Nicho!<\/p><p>Os nichos t\u00eam o incr\u00edvel poder de esticar o tamanho do seu lavabo.<\/p><p>Um lavabo com uma decora\u00e7\u00e3o embutida na parede e uma ilumina\u00e7\u00e3o direcionada deixa o ambiente ainda mais agrad\u00e1vel.<\/p><p>S\u00f3 confira antes de quebrar se a parede n\u00e3o tem fun\u00e7\u00e3o estrutural, pois a\u00ed, nesse caso: NEM PENSE EM QUEBRAR!<\/p><p>&nbsp;<\/p><figure id=\"attachment_10082\" aria-describedby=\"caption-attachment-10082\" style=\"width: 675px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-10082 size-full\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/detalhe-nicho-lavabo.jpg\" alt=\"\" width=\"675\" height=\"900\" title=\"\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/detalhe-nicho-lavabo.jpg 675w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/detalhe-nicho-lavabo-640x853.jpg 640w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/detalhe-nicho-lavabo-150x200.jpg 150w\" sizes=\"(max-width: 675px) 100vw, 675px\" \/><figcaption id=\"caption-attachment-10082\" class=\"wp-caption-text\">Nicho e ilumina\u00e7\u00e3o no lavabo<\/figcaption><\/figure><h3><strong>Ilumina\u00e7\u00e3o no lavabo<\/strong><\/h3><p>Uma boa ilumina\u00e7\u00e3o sobre a bancada \u00e9 primordial, principalmente se o lavabo tiver essa pegada mais intimista; ilumina\u00e7\u00e3o sob e sobre o espelho d\u00e1 um efeito super bonito.<\/p><p>Claro, a Ilumina\u00e7\u00e3o direcionada do nicho tamb\u00e9m \u00e9 importante, pois d\u00e1 destaque aos detalhes da decora\u00e7\u00e3o.<\/p><h3>Enxoval<\/h3><p>Quando o assunto \u00e9 decora\u00e7\u00e3o, um lavabo elegante desse merece um enxoval de acordo, n\u00e3o \u00e9 mesmo?<\/p><p>A escolha de materiais e revestimentos \u00e9 muito importante. Abuse das toalhas de rosto, sabonete l\u00edquido, sach\u00eas ou aromatizadores que s\u00e3o sempre bem vindos.<\/p><p>O feng shui tamb\u00e9m agradece!<\/p><figure id=\"attachment_10067\" aria-describedby=\"caption-attachment-10067\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/enxoval-lavabo.jpg\"><img decoding=\"async\" class=\"wp-image-10067\" title=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/enxoval-lavabo-448x330.jpg\" alt=\"Reforma de Lavabo - Como fazer a reforma dos seus sonhos!\" width=\"710\" height=\"523\" \/><\/a><figcaption id=\"caption-attachment-10067\" class=\"wp-caption-text\">Enxoval para o lavabo<\/figcaption><\/figure><figure id=\"attachment_10064\" aria-describedby=\"caption-attachment-10064\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/kit-lavabo.jpg\"><img decoding=\"async\" class=\"wp-image-10064 size-full\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/kit-lavabo.jpg\" alt=\"\" width=\"900\" height=\"600\" title=\"\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/kit-lavabo.jpg 900w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/kit-lavabo-696x464.jpg 696w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/kit-lavabo-150x100.jpg 150w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><figcaption id=\"caption-attachment-10064\" class=\"wp-caption-text\">Kit lavabo<\/figcaption><\/figure><figure id=\"attachment_10061\" aria-describedby=\"caption-attachment-10061\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-10061 size-full\" src=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-detalhe-2.png\" alt=\"\" width=\"900\" height=\"1200\" title=\"\" srcset=\"https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-detalhe-2.png 900w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-detalhe-2-768x1024.png 768w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-detalhe-2-696x928.png 696w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-detalhe-2-640x853.png 640w, https:\/\/www.aarquiteta.com.br\/blog\/wp-content\/uploads\/2017\/03\/lavabo-detalhe-2-150x200.png 150w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-10061\" class=\"wp-caption-text\">Projeto completo do lavabo<\/figcaption><\/figure><p>Se voc\u00ea curtiu essas dicas e adora um quebra-quebra, confira o artigo que preparei sobre <a href=\"https:\/\/www.aarquiteta.com.br\/blog\/design-de-interiores\/etapas-de-uma-reforma-de-apartamento\/\">as 13 etapas de uma reforma de um apartamento<\/a>.<\/p><p>Tenho certeza que podem te ajudar muito caso esteja pensando em fazer uma reforma de grande porte.<\/p><p>Mas se voc\u00ea est\u00e1 precisando aprender a criar espa\u00e7os no design de interiores, confira s\u00f3 esta dica que preparamos para voc\u00ea:<\/p><h5>Se voc\u00ea gosta de cozinhar que tal come\u00e7ar a decorar?<\/h5><p>Assista este v\u00eddeo abaixo e aprenda estas <a href=\"https:\/\/br.pinterest.com\/aarquitetapinterest\/_created\/\" target=\"_blank\" rel=\"noopener\">dicas valiosas<\/a> para transformar sua casa!<\/p><h3>E a\u00ed, gostou do artigo Reforma de Lavabo &#8211; Como fazer a reforma dos seus sonhos?<\/h3><p>Ent\u00e3o deslize a tela para baixo e<a href=\"https:\/\/br.pinterest.com\/aarquitetapinterest\/_created\/\" target=\"_blank\" rel=\"noopener\"> confira mais dicas<\/a> como esta e n\u00e3o se esque\u00e7a de compartilhar com os amigos!<\/p><p>Quer mais dicas sobre o mundo da Arquitetura e Decora\u00e7\u00e3o? Ent\u00e3o decore f\u00e1cil sem mist\u00e9rios, confira alguns dos nossos artigos em:<\/p><ul><li style=\"list-style-type: none;\"><ul><li><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/paisagismo\/\" target=\"_blank\" rel=\"noopener\">Casa e Jardim<\/a><\/li><li><a href=\"https:\/\/www.aarquiteta.com.br\/blog\/arquitetura\/mundo-arquitetura\/\" target=\"_blank\" rel=\"noopener\">Mundo Arquitetura<\/a><\/li><li><a href=\"https:\/\/www.aarquiteta.com.br\/decoracao\/\" target=\"_blank\" rel=\"noopener\">Decora\u00e7\u00e3o<br \/>\n<\/a><\/li><\/ul><\/li><\/ul><p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Reforma de Lavabo \u2014 Como fazer a reforma dos seus sonhos!Lavabo: seja ele pequeno, bonito e funcional muitas vezes n\u00e3o \u00e9 t\u00e3o dif\u00edcil deix\u00e1-lo como imaginamos.Com a infinidade de op\u00e7\u00f5es de recursos, objetos de decora\u00e7\u00e3o e utens\u00edlios que temos no mercado \u00e9 poss\u00edvel realizar muito com pouco.No entanto, para criar um ambiente que realmente inspire [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":10192,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[971,19127],"tags":[13052,13051,13053],"class_list":["post-10050","post","type-post","status-publish","format-standard","has-post-thumbnail","category-design-de-interiores","category-reforma-e-manutencao","tag-como-decorar-lavabo","tag-decoracao-de-lavabo","tag-decoracao-lavabo-pequeno"],"_wp_attached_file":null,"_wp_attachment_metadata":null,"_wp_attachment_context":null,"_wp_attachment_is_custom_header":null,"geo_longitude":null,"geo_public":null,"geo_latitude":null,"_publicize_done_external":null,"_wpas_done_3897181":null,"publicize_twitter_user":null,"_wpas_done_3897175":null,"_wpas_skip_3897181":null,"_wpas_skip_3897175":null,"_wpas_skip_3924723":null,"_wpas_mess":null,"_wpas_done_3924723":null,"wps_subtitle":"Confira as melhores dicas de Decora\u00e7\u00e3o que separamos para voc\u00ea decorar sua casa e deix\u00e1-la ainda mais aconchegante!","_links":{"self":[{"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/posts\/10050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=10050"}],"version-history":[{"count":0,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/posts\/10050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/media\/10192"}],"wp:attachment":[{"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=10050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=10050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aarquiteta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=10050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}